{"id":3222,"date":"2024-07-04T16:32:01","date_gmt":"2024-07-04T14:32:01","guid":{"rendered":"https:\/\/langtvvla.com.ar\/?p=3222"},"modified":"2024-07-04T16:43:10","modified_gmt":"2024-07-04T14:43:10","slug":"sociedad-hector-pino-y-su-verdad","status":"publish","type":"post","link":"https:\/\/langtvvla.com.ar\/index.php\/2024\/07\/04\/sociedad-hector-pino-y-su-verdad\/","title":{"rendered":"SOCIEDAD: HECTOR PINO Y SU VERDAD"},"content":{"rendered":"\n<p><strong>En las \u00faltimas horas, muy a su pesar, el Subsecretario de Deportes de Angostura Hector Pino, se vio nombrado por algunos medios de la localidad, de no buena manera y, en alg\u00fan caso, bordeando conductas tipificadas por el C\u00f3digo Penal como delito.<\/strong><\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f10a0a\" class=\"has-inline-color\">QUE DICE EL CODIGO PENAL ARGENTINO<\/mark><\/strong><\/p>\n\n\n\n<p><a><strong>TITULO II<\/strong><\/a><\/p>\n\n\n\n<p><strong>DELITOS CONTRA EL HONOR<\/strong><\/p>\n\n\n\n<p><strong>ARTICULO 109.\u00a0&#8211; La calumnia o falsa imputaci\u00f3n a una persona f\u00edsica determinada de la comisi\u00f3n de un delito concreto y circunstanciado que d\u00e9 lugar a la acci\u00f3n p\u00fablica, ser\u00e1 reprimida con multa de pesos tres mil ($ 3.000.-) a pesos treinta mil ($ 30.000.-). En ning\u00fan caso configurar\u00e1n delito de calumnia las expresiones referidas a asuntos de inter\u00e9s p\u00fablico o las que no sean asertivas.<\/strong><\/p>\n\n\n\n<p><em><strong>(Art\u00edculo sustituido por art. 1\u00b0 de la\u00a0<\/strong><\/em><a href=\"https:\/\/servicios.infoleg.gob.ar\/infolegInternet\/verNorma.do?id=160774\"><strong><em>Ley N\u00b0 26.551<\/em><\/strong><\/a><em><strong>\u00a0B.O. 27\/11\/2009)<\/strong><\/em><\/p>\n\n\n\n<p><strong>ARTICULO 110.\u00a0&#8211; El que intencionalmente deshonrare o desacreditare a una persona f\u00edsica determinada ser\u00e1 reprimido con multa de pesos mil quinientos ($ 1.500.-) a pesos veinte mil ($ 20.000.-). En ning\u00fan caso configurar\u00e1n delito de injurias las expresiones referidas a asuntos de inter\u00e9s p\u00fablico o las que no sean asertivas. Tampoco configurar\u00e1n delito de injurias los calificativos lesivos del honor cuando guardasen relaci\u00f3n con un asunto de inter\u00e9s p\u00fablico.<\/strong><\/p>\n\n\n\n<p><em><strong>(Art\u00edculo sustituido por art. 2\u00b0 de la\u00a0<\/strong><\/em><a href=\"https:\/\/servicios.infoleg.gob.ar\/infolegInternet\/verNorma.do?id=160774\"><strong><em>Ley N\u00b0 26.551<\/em><\/strong><\/a><em><strong>\u00a0B.O. 27\/11\/2009)<\/strong><\/em><\/p>\n\n\n\n<p><em><strong>(Nota Infoleg:\u00a0multa actualizada por art. 1\u00b0 de la\u00a0<\/strong><\/em><a href=\"https:\/\/servicios.infoleg.gob.ar\/infolegInternet\/verNorma.do?id=684\"><strong><em>Ley N\u00b0 24.286<\/em><\/strong><\/a><em><strong>\u00a0B.O. 29\/12\/1993)<\/strong><\/em><\/p>\n\n\n\n<p><strong>ARTICULO 113.\u00a0&#8211; El que publicare o reprodujere, por cualquier medio, injurias o calumnias inferidas por otro, ser\u00e1 reprimido como autor de las injurias o calumnias de que se trate, siempre que su contenido no fuera atribuido en forma sustancialmente fiel a la fuente pertinente. En ning\u00fan caso configurar\u00e1n delito de calumnia las expresiones referidas a asuntos de inter\u00e9s p\u00fablico o las que no sean asertivas.<\/strong><\/p>\n\n\n\n<p><em><strong>(Art\u00edculo sustituido por art. 5\u00b0 de la\u00a0<\/strong><\/em><a href=\"https:\/\/servicios.infoleg.gob.ar\/infolegInternet\/verNorma.do?id=160774\"><strong><em>Ley N\u00b0 26.551<\/em><\/strong><\/a><em><strong>\u00a0B.O. 27\/11\/2009)<\/strong><\/em><\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f50404\" class=\"has-inline-color\">LA NOTA DE HECTOR PINO HECHA PUBLICA<\/mark><\/strong><\/p>\n\n\n\n<p><strong>Debido a la publicaci\u00f3n hecha en un medio es que el Subsecretario redact\u00f3 est\u00e1 nota que fue publicada. Aqu\u00ed la reproducimos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"531\" height=\"1024\" src=\"https:\/\/langtvvla.com.ar\/wp-content\/uploads\/2024\/07\/Screenshot_20240704_113548_Chrome-531x1024.jpg\" alt=\"\" class=\"wp-image-3225\" srcset=\"https:\/\/langtvvla.com.ar\/wp-content\/uploads\/2024\/07\/Screenshot_20240704_113548_Chrome-531x1024.jpg 531w, https:\/\/langtvvla.com.ar\/wp-content\/uploads\/2024\/07\/Screenshot_20240704_113548_Chrome-156x300.jpg 156w, https:\/\/langtvvla.com.ar\/wp-content\/uploads\/2024\/07\/Screenshot_20240704_113548_Chrome.jpg 720w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.diarioandino.com.ar\/noticias\/2024\/07\/02\/228397-con-una-topadora-propietarios-lograron-ingresar-a-una-casa-usurpada-y-recuperarla-video\">https:\/\/www.diarioandino.com.ar\/noticias\/2024\/07\/02\/228397-con-una-topadora-propietarios-lograron-ingresar-a-una-casa-usurpada-y-recuperarla-video<\/a><\/p>\n\n\n\n<p><strong>3 de julio de 2024<\/strong><\/p>\n\n\n\n<p><strong>Sr. Director<\/strong><\/p>\n\n\n\n<p><strong>Por medio de la presente me dirijo a Ud. con motivo de la Nota Periodistica publicada en el dia de ayer 2 de julio de 2024, en la cual manifiestan que yo tendr\u00eda en mi contra una denuncia por usurpaci\u00f3n, dato que es totalmente falso y entiendo esta siendo utilizado por los denunciantes y sus abogados, tratando de montar un show medi\u00e1tico.<br>Desde ya vengo a solicitar la publicaci\u00f3n de la presente nota a los efectos de que p\u00fablicamente quede claro que NUNCA fui denunciado por ning\u00fan delito y que la denuncia a la que refiere la nota, es contra mi padre que resulta hom\u00f3nimo m\u00edo y titular del inmueble en el que los denunciantes de fecha 3 de junio y que ayer ingresaran con una m\u00e1quina cargadora en calle Blvd. Quetrihue 756.-<br>Por \u00faltimo es dable destacar que de acuerdo a la documentaci\u00f3n con la que cuenta mi padre y del cual soy apoderado, la porci\u00f3n del inmueble que refieren los denunciantes es de su propiedad por venta que le realizara mi padre hace varios a\u00f1os y por supuesto falso que mi padre o nadie les haya usurpado.-<br>Habiendo aclarado esto en los medios entiendo que el resto deber\u00e1n resolverlo en la justicia tanto mi padre como los denunciantes, no teniendo m\u00e1s para aclarar por este medio.<br>Reservando mi derecho de accionar por las falsas acusaciones hacia mi persona, mi familia , quedando a disposici\u00f3n de la justicia como siempre he estado para responder. Quiero dejar en claro que no tengo ninguna imputaci\u00f3n en mi contra y con esto dejar limpio mi buen nombre y reputaci\u00f3n como vecino y funcionario p\u00fablico de este municipio.y agradecer a todos los mensajes de apoyo personalmente que he tenido.<\/strong><\/p>\n\n\n\n<p><strong>CREDITO FOTOS WEB<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las \u00faltimas horas, muy a su pesar, el Subsecretario de Deportes de Angostura Hector Pino, se vio nombrado por algunos medios de la localidad, de no buena manera y, en alg\u00fan caso, bordeando conductas tipificadas por el C\u00f3digo Penal como delito. QUE DICE EL CODIGO PENAL ARGENTINO TITULO II DELITOS CONTRA EL HONOR ARTICULO [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,42,36],"tags":[],"class_list":["post-3222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justicia","category-medios","category-sociedad"],"_links":{"self":[{"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3222"}],"version-history":[{"count":2,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3222\/revisions"}],"predecessor-version":[{"id":3227,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3222\/revisions\/3227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/media\/3226"}],"wp:attachment":[{"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/langtvvla.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}